{"id":10660,"date":"2026-03-11T11:15:57","date_gmt":"2026-03-11T16:15:57","guid":{"rendered":"https:\/\/amcham.org.pe\/news\/?p=10660"},"modified":"2026-03-11T11:15:57","modified_gmt":"2026-03-11T16:15:57","slug":"asocem-despacho-de-cemento-crecio-en-febrero","status":"publish","type":"post","link":"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/","title":{"rendered":"Asocem: despacho de cemento creci\u00f3 en febrero"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[395,736,61,11,429],"class_list":["post-10660","post","type-post","status-publish","format-standard","hentry","category-economia","tag-amcham-peru","tag-cemento","tag-construccion","tag-economia","tag-inversion-privada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"El despacho nacional de cemento registr\u00f3 un crecimiento en febrero del 2026, reflejando el dinamismo que viene mostrando el sector construcci\u00f3n en los \u00faltimos meses. Seg\u00fan el reporte estad\u00edstico mensual de la Asociaci\u00f3n de Productores de Cemento (Asocem), el despacho nacional alcanz\u00f3 aproximadamente 1,07 millones de toneladas m\u00e9tricas, lo que represent\u00f3 un aumento frente al mismo mes del a\u00f1o anterior.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asocem: despacho de cemento creci\u00f3 en febrero - AmCham News\" \/>\n<meta property=\"og:description\" content=\"El despacho nacional de cemento registr\u00f3 un crecimiento en febrero del 2026, reflejando el dinamismo que viene mostrando el sector construcci\u00f3n en los \u00faltimos meses. Seg\u00fan el reporte estad\u00edstico mensual de la Asociaci\u00f3n de Productores de Cemento (Asocem), el despacho nacional alcanz\u00f3 aproximadamente 1,07 millones de toneladas m\u00e9tricas, lo que represent\u00f3 un aumento frente al mismo mes del a\u00f1o anterior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/\" \/>\n<meta property=\"og:site_name\" content=\"AmCham News\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-11T16:15:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2023\/04\/shutterstock_426500653.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2023\/03\/shutterstock_752076598.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\",\"url\":\"https:\/\/amcham.org.pe\/news\/\",\"name\":\"Amcham News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amcham.org.pe\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/#webpage\",\"url\":\"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/\",\"name\":\"Asocem: despacho de cemento creci\\u00f3 en febrero - AmCham News\",\"isPartOf\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\"},\"datePublished\":\"2026-03-11T16:15:57+00:00\",\"dateModified\":\"2026-03-11T16:15:57+00:00\",\"author\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\"},\"description\":\"El despacho nacional de cemento registr\\u00f3 un crecimiento en febrero del 2026, reflejando el dinamismo que viene mostrando el sector construcci\\u00f3n en los \\u00faltimos meses. Seg\\u00fan el reporte estad\\u00edstico mensual de la Asociaci\\u00f3n de Productores de Cemento (Asocem), el despacho nacional alcanz\\u00f3 aproximadamente 1,07 millones de toneladas m\\u00e9tricas, lo que represent\\u00f3 un aumento frente al mismo mes del a\\u00f1o anterior.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amcham.org.pe\/news\/asocem-despacho-de-cemento-crecio-en-febrero\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\",\"name\":\"Administrador\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/comments?post=10660"}],"version-history":[{"count":1,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10660\/revisions"}],"predecessor-version":[{"id":10661,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10660\/revisions\/10661"}],"wp:attachment":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/media?parent=10660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/categories?post=10660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/tags?post=10660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}