{"id":10954,"date":"2026-04-07T10:31:26","date_gmt":"2026-04-07T15:31:26","guid":{"rendered":"https:\/\/amcham.org.pe\/news\/?p=10954"},"modified":"2026-04-07T10:31:26","modified_gmt":"2026-04-07T15:31:26","slug":"inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026","status":"publish","type":"post","link":"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/","title":{"rendered":"Inversi\u00f3n p\u00fablica en Per\u00fa alcanza r\u00e9cord hist\u00f3rico en el primer trimestre del 2026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[395,11,449,182],"class_list":["post-10954","post","type-post","status-publish","format-standard","hentry","category-economia","tag-amcham-peru","tag-economia","tag-inversion-publica","tag-mef"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"La inversi\u00f3n p\u00fablica en el Per\u00fa registr\u00f3 un m\u00e1ximo hist\u00f3rico durante el primer trimestre de 2026, consolidando el mayor nivel de ejecuci\u00f3n para este periodo del a\u00f1o. Seg\u00fan datos del Ministerio de Econom\u00eda y Finanzas del Per\u00fa (MEF), el gasto en proyectos de inversi\u00f3n alcanz\u00f3 S\/ 11,641 millones entre enero y marzo, lo que representa un crecimiento de 3,5% frente al mismo periodo de 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inversi\u00f3n p\u00fablica en Per\u00fa alcanza r\u00e9cord hist\u00f3rico en el primer trimestre del 2026 - AmCham News\" \/>\n<meta property=\"og:description\" content=\"La inversi\u00f3n p\u00fablica en el Per\u00fa registr\u00f3 un m\u00e1ximo hist\u00f3rico durante el primer trimestre de 2026, consolidando el mayor nivel de ejecuci\u00f3n para este periodo del a\u00f1o. Seg\u00fan datos del Ministerio de Econom\u00eda y Finanzas del Per\u00fa (MEF), el gasto en proyectos de inversi\u00f3n alcanz\u00f3 S\/ 11,641 millones entre enero y marzo, lo que representa un crecimiento de 3,5% frente al mismo periodo de 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"AmCham News\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T15:31:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2023\/05\/shutterstock_723993466.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2023\/05\/shutterstock_723993466.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\",\"url\":\"https:\/\/amcham.org.pe\/news\/\",\"name\":\"Amcham News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amcham.org.pe\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/#webpage\",\"url\":\"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/\",\"name\":\"Inversi\\u00f3n p\\u00fablica en Per\\u00fa alcanza r\\u00e9cord hist\\u00f3rico en el primer trimestre del 2026 - AmCham News\",\"isPartOf\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\"},\"datePublished\":\"2026-04-07T15:31:26+00:00\",\"dateModified\":\"2026-04-07T15:31:26+00:00\",\"author\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\"},\"description\":\"La inversi\\u00f3n p\\u00fablica en el Per\\u00fa registr\\u00f3 un m\\u00e1ximo hist\\u00f3rico durante el primer trimestre de 2026, consolidando el mayor nivel de ejecuci\\u00f3n para este periodo del a\\u00f1o. Seg\\u00fan datos del Ministerio de Econom\\u00eda y Finanzas del Per\\u00fa (MEF), el gasto en proyectos de inversi\\u00f3n alcanz\\u00f3 S\/ 11,641 millones entre enero y marzo, lo que representa un crecimiento de 3,5% frente al mismo periodo de 2025.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amcham.org.pe\/news\/inversion-publica-en-peru-alcanza-record-historico-en-el-primer-trimestre-del-2026\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\",\"name\":\"Administrador\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/comments?post=10954"}],"version-history":[{"count":1,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10954\/revisions"}],"predecessor-version":[{"id":10955,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/10954\/revisions\/10955"}],"wp:attachment":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/media?parent=10954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/categories?post=10954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/tags?post=10954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}