{"id":1096,"date":"2020-08-06T15:00:27","date_gmt":"2020-08-06T20:00:27","guid":{"rendered":"https:\/\/amcham.org.pe\/news\/?p=1096"},"modified":"2022-05-04T18:37:04","modified_gmt":"2022-05-04T23:37:04","slug":"equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn","status":"publish","type":"post","link":"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/","title":{"rendered":"Equifax Per\u00fa: \u00abEl trabajo colaborativo se ha fortalecido; est\u00e1 en nuestro ADN\u00bb"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[18,64,8,69],"class_list":["post-1096","post","type-post","status-publish","format-standard","hentry","category-especiales","tag-covid-19","tag-entrevista-al-ceo","tag-gestion","tag-sector-financiero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v14.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equifax Per\u00fa: &quot;El trabajo colaborativo se ha fortalecido; est\u00e1 en nuestro ADN&quot; - AmCham News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/\" \/>\n<meta property=\"og:site_name\" content=\"AmCham News\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-06T20:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-04T23:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2020\/08\/AdobeStock_307209166_opt-e1628205605202.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/amcham.org.pe\/news\/wp-content\/uploads\/2020\/08\/AdobeStock_307209166_opt-e1628205605202.jpg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\",\"url\":\"https:\/\/amcham.org.pe\/news\/\",\"name\":\"Amcham News\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/amcham.org.pe\/news\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/#webpage\",\"url\":\"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/\",\"name\":\"Equifax Per\\u00fa: \\\"El trabajo colaborativo se ha fortalecido; est\\u00e1 en nuestro ADN\\\" - AmCham News\",\"isPartOf\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#website\"},\"datePublished\":\"2020-08-06T20:00:27+00:00\",\"dateModified\":\"2022-05-04T23:37:04+00:00\",\"author\":{\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/amcham.org.pe\/news\/equifax-peru-el-trabajo-colaborativo-se-ha-fortalecido-esta-en-nuestro-adn\/\"]}]},{\"@type\":[\"Person\"],\"@id\":\"https:\/\/amcham.org.pe\/news\/#\/schema\/person\/c87e67b38d12c59ee4af463f78dbe2f9\",\"name\":\"Administrador\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/1096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/comments?post=1096"}],"version-history":[{"count":4,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/1096\/revisions"}],"predecessor-version":[{"id":4777,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/posts\/1096\/revisions\/4777"}],"wp:attachment":[{"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/media?parent=1096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/categories?post=1096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amcham.org.pe\/news\/wp-json\/wp\/v2\/tags?post=1096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}